{"id":39,"name":"jose","url":"http:\/\/www.brewerytek.com","description":"","link":"http:\/\/www.rr88sh.com\/blog\/author\/jose\/","slug":"jose","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a3333c9cb1de3c204aa05e3c704c71184fdde23674da7fccc2da025194cebb95?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a3333c9cb1de3c204aa05e3c704c71184fdde23674da7fccc2da025194cebb95?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a3333c9cb1de3c204aa05e3c704c71184fdde23674da7fccc2da025194cebb95?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/users\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/users"}]}}