{"id":273,"count":0,"description":"","link":"http:\/\/www.rr88sh.com\/blog\/tag\/multi-axle-special-purpose-vehicles-4426-72e7c6\/","name":"Multi-axle Special-purpose Vehicles","slug":"multi-axle-special-purpose-vehicles-4426-72e7c6","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/tags\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.rr88sh.com\/blog\/wp-json\/wp\/v2\/posts?tags=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}